{"id":1092,"date":"2018-11-05T13:34:04","date_gmt":"2018-11-05T16:34:04","guid":{"rendered":"https:\/\/2018.montevideo.wordcamp.org\/?post_type=wcb_sponsor&#038;p=1092"},"modified":"2018-11-05T13:34:04","modified_gmt":"2018-11-05T16:34:04","slug":"montevideo-portal","status":"publish","type":"wcb_sponsor","link":"https:\/\/montevideo.wordcamp.org\/2018\/sponsor\/montevideo-portal\/","title":{"rendered":"Montevideo Portal"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1093,"template":"","meta":{"_crdt_document":"","_wcpt_sponsor_website":"http:\/\/www.montevideo.com.uy","footnotes":""},"sponsor_level":[33637],"class_list":["post-1092","wcb_sponsor","type-wcb_sponsor","status-publish","has-post-thumbnail","hentry","wcb_sponsor_level-media-partners"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMLp-hC","_links":{"self":[{"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/sponsors\/1092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/sponsors"}],"about":[{"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/wcb_sponsor"}],"version-history":[{"count":1,"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/sponsors\/1092\/revisions"}],"predecessor-version":[{"id":1094,"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/sponsors\/1092\/revisions\/1094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/media\/1093"}],"wp:attachment":[{"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=1092"}],"wp:term":[{"taxonomy":"wcb_sponsor_level","embeddable":true,"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/sponsor_level?post=1092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}