{"id":1114,"date":"2018-11-06T19:04:36","date_gmt":"2018-11-06T22:04:36","guid":{"rendered":"https:\/\/2018.montevideo.wordcamp.org\/?post_type=wcb_sponsor&#038;p=1114"},"modified":"2018-11-07T00:19:55","modified_gmt":"2018-11-07T03:19:55","slug":"jam3","status":"publish","type":"wcb_sponsor","link":"https:\/\/montevideo.wordcamp.org\/2018\/sponsor\/jam3\/","title":{"rendered":"Jam3"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1115,"template":"","meta":{"_crdt_document":"","_wcpt_sponsor_website":"http:\/\/www.jam3.com","footnotes":""},"sponsor_level":[1267482],"class_list":["post-1114","wcb_sponsor","type-wcb_sponsor","status-publish","has-post-thumbnail","hentry","wcb_sponsor_level-tutor"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMLp-hY","_links":{"self":[{"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/sponsors\/1114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/sponsors"}],"about":[{"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/wcb_sponsor"}],"version-history":[{"count":1,"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/sponsors\/1114\/revisions"}],"predecessor-version":[{"id":1116,"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/sponsors\/1114\/revisions\/1116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/media\/1115"}],"wp:attachment":[{"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=1114"}],"wp:term":[{"taxonomy":"wcb_sponsor_level","embeddable":true,"href":"https:\/\/montevideo.wordcamp.org\/2018\/wp-json\/wp\/v2\/sponsor_level?post=1114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}